{"id":2508,"date":"2022-09-09T20:20:56","date_gmt":"2022-09-09T23:20:56","guid":{"rendered":"https:\/\/sistemafaepa.com.br\/fundepec\/2022\/09\/09\/nucleo-guajarina-castanhal-inaugura-centro-integrado-de-producao-estacao-cidadania-neste-sabado-em-meio-a-53o-expofac\/"},"modified":"2022-09-09T20:20:56","modified_gmt":"2022-09-09T23:20:56","slug":"nucleo-guajarina-castanhal-inaugura-centro-integrado-de-producao-estacao-cidadania-neste-sabado-em-meio-a-53o-expofac","status":"publish","type":"post","link":"https:\/\/sistemafaepa.com.br\/fundepec\/2022\/09\/09\/nucleo-guajarina-castanhal-inaugura-centro-integrado-de-producao-estacao-cidadania-neste-sabado-em-meio-a-53o-expofac\/","title":{"rendered":"N\u00facleo Guajarina: Castanhal inaugura Centro Integrado de Produ\u00e7\u00e3o\/ Esta\u00e7\u00e3o Cidadania neste s\u00e1bado em meio a 53\u00ba EXPOFAC"},"content":{"rendered":"<p>O Secret\u00e1rio de Desenvolvimento Agropecu\u00e1rio e da Pesca (Sedap), Jo\u00e3o Carlos Le\u00e3o Ramos, e o presidente do Sistema Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Par\u00e1 (Faepa), Carlos Xavier, e demais autoridades, participam neste s\u00e1bado, dia 10 de setembro, \u00e0s 18h, no Parque de Exposi\u00e7\u00f5es de Castanhal, da Inaugura\u00e7\u00e3o do Centro Integrado de Produ\u00e7\u00e3o\/ Esta\u00e7\u00e3o Cidadania.<\/p>\n<p>O Centro Integrado de Produ\u00e7\u00e3o\/ Esta\u00e7\u00e3o Cidadania, uma rede integrada, fruto da parceria entre o Sistema Faepa\/ Senar\/ Fundepec\/ Sindicatos e o Governo do Estado do Par\u00e1, atrav\u00e9s da Secretaria Extraordin\u00e1ria de Produ\u00e7\u00e3o e da Secretaria de Estado de Desenvolvimento Agropecu\u00e1rio e da Pesca, com objetivo de disseminar o conhecimento na regi\u00e3o.<\/p>\n<p>Tamb\u00e9m s\u00e3o parceiros do projeto: produtores rurais, sindicatos, associa\u00e7\u00f5es, cooperativas, ind\u00fastrias, institui\u00e7\u00f5es de pesquisa, trabalhadores rurais e profissionais do meio acad\u00eamico.uma iniciativa do Sistema Faepa\/ Senar\/ Fundepec\/ Sindicatos e demais parceiros, que re\u00fane, em um \u00fanico local, uma variedade de \u00f3rg\u00e3os e institui\u00e7\u00f5es prestadoras de servi\u00e7os ao produtor rural, com objetivo de facilitar e agilizar o seu acesso a informa\u00e7\u00f5es e servi\u00e7os necess\u00e1rios ao bom desempenho de sua atividade.<\/p>\n<p>Na oportunidade estar\u00e3o presentes representantes de diversas institui\u00e7\u00f5es,\u00a0 presidentes de Sindicatos e produtores rurais da regi\u00e3o do N\u00facleo Guajarina.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio de Desenvolvimento Agropecu\u00e1rio e da Pesca (Sedap), Jo\u00e3o Carlos Le\u00e3o Ramos, e o presidente do Sistema Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Par\u00e1 (Faepa), Carlos Xavier, e demais autoridades, participam neste s\u00e1bado, dia 10 de setembro, \u00e0s 18h, no Parque de Exposi\u00e7\u00f5es de Castanhal, da Inaugura\u00e7\u00e3o do Centro Integrado de Produ\u00e7\u00e3o\/ Esta\u00e7\u00e3o Cidadania. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2508","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/posts\/2508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/comments?post=2508"}],"version-history":[{"count":0,"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/posts\/2508\/revisions"}],"wp:attachment":[{"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/media?parent=2508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/categories?post=2508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafaepa.com.br\/fundepec\/wp-json\/wp\/v2\/tags?post=2508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}